{"id":12,"count":7,"description":"","link":"https:\/\/lobviral.com\/it\/categoria\/giochi\/","name":"GIOCHI","slug":"giochi","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/lobviral.com\/it\/wp-json\/wp\/v2\/categories\/12","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lobviral.com\/it\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/lobviral.com\/it\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/lobviral.com\/it\/wp-json\/wp\/v2\/posts?categories=12"}],"curies":[{"name":"parola chiave","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}